{"id":120155,"date":"2026-03-03T16:15:28","date_gmt":"2026-03-03T15:15:28","guid":{"rendered":"https:\/\/rideandco.com\/giant\/?post_type=product&#038;p=120155"},"modified":"2026-05-13T06:00:57","modified_gmt":"2026-05-13T04:00:57","slug":"propel-advanced-sl-team-jayco-alula","status":"publish","type":"product","link":"https:\/\/rideandco.com\/giant\/kit-cadre\/propel-advanced-sl-team-jayco-alula\/","title":{"rendered":"Kit Cadre Propel Advanced SL Team Jayco AlUla"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Kit Cadre Propel Advanced SL Team Jayco AlUla : les points performance<\/h2>\n\n\n\n<p><strong>Int\u00e9gration a\u00e9rodynamique<br><\/strong>Gr\u00e2ce \u00e0 la technologie AeroSystem Shaping, d\u00e9velopp\u00e9e \u00e0 partir d\u2019analyses en dynamique des fluides et de tests en soufflerie, les performances a\u00e9rodynamiques sont optimis\u00e9es dans toutes les situations. Les tubes \u00e0 profil elliptique tronqu\u00e9 permettent de r\u00e9duire la tra\u00een\u00e9e tout en garantissant une efficacit\u00e9 a\u00e9rodynamique globale remarquable.<\/p>\n\n\n\n<p><strong>R\u00e9glages simplifi\u00e9s<br><\/strong>Le nouveau syst\u00e8me de passage interne des c\u00e2bles, traversant le cintre et le cadre, facilite les ajustements et le remplacement des composants du poste de pilotage. Il devient ainsi plus simple d\u2019affiner la position de conduite et d\u2019adapter le v\u00e9lo \u00e0 ses pr\u00e9f\u00e9rences.<\/p>\n\n\n\n<p><strong>Efficacit\u00e9 maximale<br><\/strong>Le cadre en composite Advanced SL est fabriqu\u00e9 avec les mat\u00e9riaux et proc\u00e9d\u00e9s les plus avanc\u00e9s de Giant, destin\u00e9s aux coureurs de haut niveau. R\u00e9sultat : un gain de 225 g par rapport \u00e0 la g\u00e9n\u00e9ration pr\u00e9c\u00e9dente, tout en augmentant la rigidit\u00e9 pour un transfert de puissance encore plus direct.<\/p>\n\n\n\n<p><strong>Le kit cadre a\u00e9ro ultime<br><\/strong>Le Propel Advanced SL Team Jayco AlUla b\u00e9n\u00e9ficie de la technologie AeroSystem Shaping pour offrir un rendement a\u00e9rodynamique optimal quelles que soient les conditions. Ses tubes \u00e0 profil elliptique tronqu\u00e9 assurent un \u00e9quilibre id\u00e9al entre rigidit\u00e9 et l\u00e9g\u00e8ret\u00e9, tandis que la tige de selle int\u00e9gr\u00e9e r\u00e9duit le poids, am\u00e9liore la p\u00e9n\u00e9tration dans l\u2019air et apporte davantage de confort sur route. Ce kit cadre rend hommage \u00e0 l\u2019\u00e9quipe Jayco AlUla avec une livr\u00e9e aux couleurs audacieuses et distinctives.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/puogjfvoquirw4sha129-1024x768.jpg\" alt=\"Kit Cadre Propel Advanced SL Team Jayco AlUla\" class=\"wp-image-120164\" srcset=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/puogjfvoquirw4sha129-1024x768.jpg 1024w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/puogjfvoquirw4sha129-300x225.jpg 300w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/puogjfvoquirw4sha129-768x576.jpg 768w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/puogjfvoquirw4sha129-1536x1152.jpg 1536w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/puogjfvoquirw4sha129-600x450.jpg 600w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/puogjfvoquirw4sha129-416x312.jpg 416w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/puogjfvoquirw4sha129.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/btmnxuwt6muhwxpr98ym-1024x768.jpg\" alt=\"Kit Cadre Propel Advanced SL Team Jayco AlUla\" class=\"wp-image-120165\" srcset=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/btmnxuwt6muhwxpr98ym-1024x768.jpg 1024w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/btmnxuwt6muhwxpr98ym-300x225.jpg 300w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/btmnxuwt6muhwxpr98ym-768x576.jpg 768w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/btmnxuwt6muhwxpr98ym-1536x1152.jpg 1536w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/btmnxuwt6muhwxpr98ym-600x450.jpg 600w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/btmnxuwt6muhwxpr98ym-416x312.jpg 416w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/btmnxuwt6muhwxpr98ym.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p><strong>Advanced Composite SL<br><\/strong>Les fibres de carbone haut de gamme utilis\u00e9es par Giant sont travaill\u00e9es dans son usine sp\u00e9cialis\u00e9e selon des proc\u00e9d\u00e9s de conception avanc\u00e9s. La technologie de fibres unidirectionnelles permet d\u2019optimiser la rigidit\u00e9 tout en r\u00e9duisant le poids. Une r\u00e9sine nano-technologique renforce la r\u00e9sistance aux impacts, tandis que le proc\u00e9d\u00e9 d\u2019assemblage par fusion garantit des jonctions plus l\u00e9g\u00e8res et plus solides.<\/p>\n\n\n\n<p><strong>AeroSystem Shaping<br><\/strong>Les profils des tubes sont \u00e9labor\u00e9s \u00e0 partir d\u2019analyses en m\u00e9canique des fluides num\u00e9rique et valid\u00e9s en soufflerie. Chaque forme est pr\u00e9cis\u00e9ment \u00e9tudi\u00e9e afin d\u2019offrir un rendement a\u00e9rodynamique optimal.<\/p>\n\n\n\n<p><strong>OverDrive Aero<br><\/strong>Int\u00e9gr\u00e9 \u00e0 la douille de direction du Propel Advanced SL Team Jayco AlUla, le pivot de fourche en forme de D associ\u00e9 \u00e0 des entretoises sp\u00e9cifiques cr\u00e9e un ensemble particuli\u00e8rement a\u00e9rodynamique, tout en facilitant le passage interne des c\u00e2bles et des gaines.<\/p>\n\n\n\n<p><strong>Tige de selle int\u00e9gr\u00e9e<br><\/strong>\u00c9l\u00e9ment cl\u00e9 des performances, la tige de selle int\u00e9gr\u00e9e permet de r\u00e9duire le poids d\u2019environ 45 g par rapport \u00e0 une tige en composite classique. Elle am\u00e9liore \u00e9galement la p\u00e9n\u00e9tration dans l\u2019air et apporte une flexibilit\u00e9 ma\u00eetris\u00e9e pour att\u00e9nuer les vibrations sur route.<\/p>\n\n\n \n <!-- G\u00e9n\u00e9rer le bouton avec les classes appropri\u00e9es -->\n <a href=\"https:\/\/www.giant-bicycles.com\/fr\/registration\" class=\"custom-button custom-button-style2\" target=\"_blank\" rel=\"noopener\">\n     <span class=\"custom-button-text\">Enregistrez votre v\u00e9lo pour la garantie !<\/span>\n      <\/a>\n \n\n \n <!-- G\u00e9n\u00e9rer le bouton avec les classes appropri\u00e9es -->\n <a href=\"https:\/\/rideandco.com\/contacts-et-acces\" class=\"custom-button custom-button-style1\">\n     <span class=\"custom-button-text\">Contactez notre \u00e9quipe !<\/span>\n      <\/a>\n \n\n\n<h2 class=\"wp-block-heading\">Ces v\u00e9los pourraient vous plaire<\/h2>\n\n\n<div id=\"product-slider-6a04abe878a95\" class=\"product-grid-custom-slider\"><div class=\"slider-wrapper\"><div class=\"slider-slide\"><!-- Valeur r\u00e9cup\u00e9r\u00e9e : PROMO --><li style=\"padding-left: 0px;\n    margin-bottom: 10px;\" class=\"custom-product-card no-before product type-product post-120404 status-publish first instock product_cat-propel product_cat-giant product_cat-velo-route product_cat-performance has-post-thumbnail sold-individually taxable shipping-taxable purchasable product-type-variable\">\n    <div class=\"custom-product-card-content\">\n                <div class=\"product-image\">\n                            <div id=\"carousel-120404\" class=\"carousel\" data-product-id=\"120404\">\n                    <div class=\"carousel-inner\">\n                        <div class=\"carousel-item active\">\n                            <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-1-2027\/\">\n                                <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/propeladv1.jpg\" alt=\"Propel Advanced 1 2027\">\n                            <\/a>\n                        <\/div>\n                                                    <div class=\"carousel-item\">\n                                <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-1-2027\/\">\n                                    <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/propaladv111.jpg\" alt=\"Propel Advanced 1 2027\">\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"carousel-item\">\n                                <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-1-2027\/\">\n                                    <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/propaladv1127.jpg\" alt=\"Propel Advanced 1 2027\">\n                                <\/a>\n                            <\/div>\n                                            <\/div>\n                    <button class=\"carousel-control-prev\" data-target=\"#carousel-120404\" aria-label=\"Previous\">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/fleche-gauche-blanche.svg\" alt=\"Pr\u00e9c\u00e9dent\" style=\"width: 60px; height: 60px;\">\n                    <\/button>\n                    <button class=\"carousel-control-next\" data-target=\"#carousel-120404\" aria-label=\"Next\">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/fleche-droite-blanche.svg\" alt=\"Suivant\" style=\"width: 60px; height: 60px;\">\n                    <\/button>\n                <\/div>\n                <div class=\"carousel-indicators\" data-target=\"#carousel-120404\">\n                    <span class=\"active\"><\/span>\n                                            <span><\/span>\n                                            <span><\/span>\n                                    <\/div>\n                    <\/div>\n        <div class=\"product-info\">\n            <h2 class=\"woocommerce-loop-product__title\">\n                <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-1-2027\/\">Propel Advanced 1 2027<\/a>\n            <\/h2>\n                            <p class=\"product-type-de-velo\">V\u00e9lo performance | GIANT <\/p>\n                       \n            <div class=\"product-icons\">\n                                                                    <div class=\"icon-wrapper first-item\">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/poids.svg\" alt=\"Weight Icon\" class=\"icon-with-tooltip\">\n                        <div class=\"tooltip custom-tooltip\">8.8kg en taille M <\/div>\n                    <\/div>\n                                                                        <div class=\"icon-wrapper \">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/type_de_jantes.svg\" alt=\"Jantes Icon\" class=\"icon-with-tooltip\">\n                        <div class=\"tooltip custom-tooltip\">Carbone <\/div>\n                    <\/div>\n                                                                <\/div>           \n            <!-- Ajouter le tarif du produit ici -->\n            <!-- Affichage du prix -->\n            <div class=\"product-price-container\">\n                <div class=\"product-price-wrapper\">\n                    <span class=\"current-price\">4 200,00 \u20ac<sup>TTC<\/sup><\/span>                <\/div>\n\n                <!-- Affichage du financement mensuel -->\n                <div class=\"product-financing\">\n                    D\u00e8s <span class=\"monthly-paymentlist\">350\u20ac\/mois<\/span> financement sur 12 mois                <\/div>\n            <\/div>\n\n            <!-- Ajoutez ici vos options suppl\u00e9mentaires -->\n            <div class=\"product-options\">\n                <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-1-2027\/\" class=\"clickable-link\">\n                    Voir ce v\u00e9lo\n                    <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/fleche-droite-verte.svg\" alt=\"Fl\u00e8che droite\" class=\"arrow-icon\">\n                <\/a>\n                <div class=\"product-compare\" data-id=\"120404\">\n                    <a href=\"javascript:addToComparator(120404)\"\n                        class=\"link-add \">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/ajouter_au_comparateur.svg\"\n                            alt=\"Ajouter au comparateur\"\n                        \/>\n                    <\/a>\n                    <a href=\"javascript:removeFromComparator(120404)\"\n                        class=\"link-remove hidden\">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/retirer_du_comparateur_rouge.svg\"\n                            alt=\"Retirer du comparateur\"\n                        \/>\n                    <\/a>\n                    <span class=\"tooltip tooltip-add \">\n                        Ajouter au comparateur\n                    <\/span>\n                    <span class=\"tooltip tooltip-remove hidden\">\n                        Retirer du comparateur\n                    <\/span>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/li><!-- Valeur r\u00e9cup\u00e9r\u00e9e : PROMO --><li style=\"padding-left: 0px;\n    margin-bottom: 10px;\" class=\"custom-product-card no-before product type-product post-120387 status-publish instock product_cat-propel product_cat-giant product_cat-velo-route product_cat-performance has-post-thumbnail sold-individually taxable shipping-taxable purchasable product-type-variable\">\n    <div class=\"custom-product-card-content\">\n                <div class=\"product-image\">\n                            <div id=\"carousel-120387\" class=\"carousel\" data-product-id=\"120387\">\n                    <div class=\"carousel-inner\">\n                        <div class=\"carousel-item active\">\n                            <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-pro-0-di2-2\/\">\n                                <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/propeladvpro0di2.jpg\" alt=\"Propel Advanced Pro 0 Di2\">\n                            <\/a>\n                        <\/div>\n                                                    <div class=\"carousel-item\">\n                                <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-pro-0-di2-2\/\">\n                                    <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/propeladvpro0di22.jpg\" alt=\"Propel Advanced Pro 0 Di2\">\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"carousel-item\">\n                                <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-pro-0-di2-2\/\">\n                                    <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/propeladvpro0di222.jpg\" alt=\"Propel Advanced Pro 0 Di2\">\n                                <\/a>\n                            <\/div>\n                                            <\/div>\n                    <button class=\"carousel-control-prev\" data-target=\"#carousel-120387\" aria-label=\"Previous\">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/fleche-gauche-blanche.svg\" alt=\"Pr\u00e9c\u00e9dent\" style=\"width: 60px; height: 60px;\">\n                    <\/button>\n                    <button class=\"carousel-control-next\" data-target=\"#carousel-120387\" aria-label=\"Next\">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/fleche-droite-blanche.svg\" alt=\"Suivant\" style=\"width: 60px; height: 60px;\">\n                    <\/button>\n                <\/div>\n                <div class=\"carousel-indicators\" data-target=\"#carousel-120387\">\n                    <span class=\"active\"><\/span>\n                                            <span><\/span>\n                                            <span><\/span>\n                                    <\/div>\n                    <\/div>\n        <div class=\"product-info\">\n            <h2 class=\"woocommerce-loop-product__title\">\n                <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-pro-0-di2-2\/\">Propel Advanced Pro 0 Di2<\/a>\n            <\/h2>\n                            <p class=\"product-type-de-velo\">V\u00e9lo performance | GIANT <\/p>\n                       \n            <div class=\"product-icons\">\n                                                                    <div class=\"icon-wrapper first-item\">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/poids.svg\" alt=\"Weight Icon\" class=\"icon-with-tooltip\">\n                        <div class=\"tooltip custom-tooltip\">7.1kg en taille M <\/div>\n                    <\/div>\n                                                                        <div class=\"icon-wrapper \">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/type_de_jantes.svg\" alt=\"Jantes Icon\" class=\"icon-with-tooltip\">\n                        <div class=\"tooltip custom-tooltip\">Carbone <\/div>\n                    <\/div>\n                                                                <\/div>           \n            <!-- Ajouter le tarif du produit ici -->\n            <!-- Affichage du prix -->\n            <div class=\"product-price-container\">\n                <div class=\"product-price-wrapper\">\n                    <span class=\"current-price\">6 600,00 \u20ac<sup>TTC<\/sup><\/span>                <\/div>\n\n                <!-- Affichage du financement mensuel -->\n                <div class=\"product-financing\">\n                    D\u00e8s <span class=\"monthly-paymentlist\">550\u20ac\/mois<\/span> financement sur 12 mois                <\/div>\n            <\/div>\n\n            <!-- Ajoutez ici vos options suppl\u00e9mentaires -->\n            <div class=\"product-options\">\n                <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-pro-0-di2-2\/\" class=\"clickable-link\">\n                    Voir ce v\u00e9lo\n                    <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/fleche-droite-verte.svg\" alt=\"Fl\u00e8che droite\" class=\"arrow-icon\">\n                <\/a>\n                <div class=\"product-compare\" data-id=\"120387\">\n                    <a href=\"javascript:addToComparator(120387)\"\n                        class=\"link-add \">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/ajouter_au_comparateur.svg\"\n                            alt=\"Ajouter au comparateur\"\n                        \/>\n                    <\/a>\n                    <a href=\"javascript:removeFromComparator(120387)\"\n                        class=\"link-remove hidden\">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/retirer_du_comparateur_rouge.svg\"\n                            alt=\"Retirer du comparateur\"\n                        \/>\n                    <\/a>\n                    <span class=\"tooltip tooltip-add \">\n                        Ajouter au comparateur\n                    <\/span>\n                    <span class=\"tooltip tooltip-remove hidden\">\n                        Retirer du comparateur\n                    <\/span>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/li><!-- Valeur r\u00e9cup\u00e9r\u00e9e : PROMO --><li style=\"padding-left: 0px;\n    margin-bottom: 10px;\" class=\"custom-product-card no-before product type-product post-120369 status-publish last outofstock product_cat-propel product_cat-giant product_cat-velo-route product_cat-performance has-post-thumbnail sold-individually taxable shipping-taxable purchasable product-type-variable\">\n    <div class=\"custom-product-card-content\">\n                <div class=\"product-image\">\n                            <div id=\"carousel-120369\" class=\"carousel\" data-product-id=\"120369\">\n                    <div class=\"carousel-inner\">\n                        <div class=\"carousel-item active\">\n                            <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-0-axs\/\">\n                                <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/propeladvancedaxs.jpg\" alt=\"Propel Advanced Pro 0 AXS\">\n                            <\/a>\n                        <\/div>\n                                                    <div class=\"carousel-item\">\n                                <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-0-axs\/\">\n                                    <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/propeladvaxsss.jpg\" alt=\"Propel Advanced Pro 0 AXS\">\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"carousel-item\">\n                                <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-0-axs\/\">\n                                    <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2026\/03\/propaladvaxss.jpg\" alt=\"Propel Advanced Pro 0 AXS\">\n                                <\/a>\n                            <\/div>\n                                            <\/div>\n                    <button class=\"carousel-control-prev\" data-target=\"#carousel-120369\" aria-label=\"Previous\">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/fleche-gauche-blanche.svg\" alt=\"Pr\u00e9c\u00e9dent\" style=\"width: 60px; height: 60px;\">\n                    <\/button>\n                    <button class=\"carousel-control-next\" data-target=\"#carousel-120369\" aria-label=\"Next\">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/fleche-droite-blanche.svg\" alt=\"Suivant\" style=\"width: 60px; height: 60px;\">\n                    <\/button>\n                <\/div>\n                <div class=\"carousel-indicators\" data-target=\"#carousel-120369\">\n                    <span class=\"active\"><\/span>\n                                            <span><\/span>\n                                            <span><\/span>\n                                    <\/div>\n                    <\/div>\n        <div class=\"product-info\">\n            <h2 class=\"woocommerce-loop-product__title\">\n                <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-0-axs\/\">Propel Advanced Pro 0 AXS<\/a>\n            <\/h2>\n                            <p class=\"product-type-de-velo\">V\u00e9lo performance | GIANT <\/p>\n                       \n            <div class=\"product-icons\">\n                                                                    <div class=\"icon-wrapper first-item\">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/poids.svg\" alt=\"Weight Icon\" class=\"icon-with-tooltip\">\n                        <div class=\"tooltip custom-tooltip\">7kg en taille M <\/div>\n                    <\/div>\n                                                                        <div class=\"icon-wrapper \">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/type_de_jantes.svg\" alt=\"Jantes Icon\" class=\"icon-with-tooltip\">\n                        <div class=\"tooltip custom-tooltip\">Carbone <\/div>\n                    <\/div>\n                                                                <\/div>           \n            <!-- Ajouter le tarif du produit ici -->\n            <!-- Affichage du prix -->\n            <div class=\"product-price-container\">\n                <div class=\"product-price-wrapper\">\n                    <span class=\"current-price\">6 600,00 \u20ac<sup>TTC<\/sup><\/span>                <\/div>\n\n                <!-- Affichage du financement mensuel -->\n                <div class=\"product-financing\">\n                    D\u00e8s <span class=\"monthly-paymentlist\">550\u20ac\/mois<\/span> financement sur 12 mois                <\/div>\n            <\/div>\n\n            <!-- Ajoutez ici vos options suppl\u00e9mentaires -->\n            <div class=\"product-options\">\n                <a href=\"https:\/\/rideandco.com\/giant\/giant\/propel\/propel-advanced-0-axs\/\" class=\"clickable-link\">\n                    Voir ce v\u00e9lo\n                    <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/fleche-droite-verte.svg\" alt=\"Fl\u00e8che droite\" class=\"arrow-icon\">\n                <\/a>\n                <div class=\"product-compare\" data-id=\"120369\">\n                    <a href=\"javascript:addToComparator(120369)\"\n                        class=\"link-add \">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/ajouter_au_comparateur.svg\"\n                            alt=\"Ajouter au comparateur\"\n                        \/>\n                    <\/a>\n                    <a href=\"javascript:removeFromComparator(120369)\"\n                        class=\"link-remove hidden\">\n                        <img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/themes\/rideandco\/src\/img\/icons\/retirer_du_comparateur_rouge.svg\"\n                            alt=\"Retirer du comparateur\"\n                        \/>\n                    <\/a>\n                    <span class=\"tooltip tooltip-add \">\n                        Ajouter au comparateur\n                    <\/span>\n                    <span class=\"tooltip tooltip-remove hidden\">\n                        Retirer du comparateur\n                    <\/span>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/li><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Lancez votre sprint \u00e0 300m de l&rsquo;arriv\u00e9e, revenez sur l&rsquo;\u00e9chapp\u00e9e, attaquez : c&rsquo;est le mantra du Kit Cadre Propel Advanced SL Team Jayco AlUla<\/p>\n","protected":false},"featured_media":120158,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":true},"product_brand":[],"product_cat":[536,478,556,479,508,509],"product_tag":[],"discipline":[],"class_list":{"0":"post-120155","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kit-cadre","7":"product_cat-giant","8":"product_cat-promo","9":"product_cat-propel","10":"product_cat-velo-route","11":"product_cat-performance","13":"first","14":"instock","15":"sale","16":"sold-individually","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-variable"},"acf":{"infos_globales":{"nom_produit":"Kit Cadre Propel Advanced SL Team Jayco AlUla","marque_velo":"GIANT","annee":2026,"type_de_velo":"V\u00e9lo performance","assitance_velo":"V\u00e9lo musculaire","garantie_produit":"Cadre : \u00e0 vie \/ Composants, transmission et p\u00e9riph\u00e9riques :  2 ans","genre_du_produit":"unisexe","assurance_incluse":true,"taille__en_cm":""},"cadre_velo":{"forme_du_cadre":"Haut","cadre":"Cadre en composite SL de pointe, axe traversant 12x142 mm, tige de selle int\u00e9gr\u00e9e, freins \u00e0 disque","matiere_du_cadre":["Carbone"],"marque_de_la_fourche":"Carbone","fourche":"composite SL de pointe, pivot de fourche OverDrive Aero enti\u00e8rement en composite, axe traversant 12x100 mm, freins \u00e0 disque","amortisseur":""},"systeme_moteur":{"moteur":"","batterie":"","details-batterie":"","simulateur_autonomie":"","autonomie":"","compteur":"","chargeur":""},"transmission":{"type_de_transmission":"","Manettes_commandes_de_vitesse":"","type_de_pedalier":"","derailleur_avant":"","derailleur_arriere":"","type_de_cassette":"","type_de_chaine":""},"type_de_freins":{"frein_av":"","frein_ar":""},"roues":{"type-de-roues":"","type_de_jantes":"","matiere_jantes":"","pneus":"","moyeu_av":"","moyeu_ar":""},"cockpit_poste_de_pilotage":{"type_de_guidon":"","type_de_potence":"","type_de_selle":"","type_de_tige_de_selle":"Composite de qualit\u00e9 SL avanc\u00e9e, conception int\u00e9gr\u00e9e, d\u00e9port de -5\/+15 mm","type_de_collier_de_selle":"","type_de_poignees":""},"particularite_du_velo":{"type_de_pedales":"","accessoires_du_velo":"Support pour GPS, porte-bidons, compatible tubeless, taille de pneu maximale de 32 mm","poids":"1.39kg en taille M","poids_total_autorise":""}},"_links":{"self":[{"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/product\/120155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/comments?post=120155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/media\/120158"}],"wp:attachment":[{"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/media?parent=120155"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/product_brand?post=120155"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/product_cat?post=120155"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/product_tag?post=120155"},{"taxonomy":"discipline","embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/discipline?post=120155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}