{"id":111124,"date":"2024-03-18T16:53:46","date_gmt":"2024-03-18T15:53:46","guid":{"rendered":"http:\/\/localhost\/egrim\/?p=111124"},"modified":"2024-10-29T14:48:10","modified_gmt":"2024-10-29T13:48:10","slug":"aide-a-lachat-dun-vae-doccasion-de-200e","status":"publish","type":"post","link":"https:\/\/rideandco.com\/giant\/aide-a-lachat-dun-vae-doccasion-de-200e\/","title":{"rendered":"Tout ce que vous devez savoir sur l&rsquo;aide \u00e0 l&rsquo;achat d&rsquo;un VAE d&rsquo;occasion ou d&rsquo;un kit d&rsquo;\u00e9lectrification de 200\u20ac \u00e0 Montpellier"},"content":{"rendered":"\n<p>Plongeons dans le monde de la <strong>mobilit\u00e9 durable<\/strong> avec un <strong>sujet d&rsquo;importance<\/strong> capitale pour les <strong>r\u00e9sidents de Montpellier et sa m\u00e9tropole<\/strong> : <strong>l&rsquo;aide \u00e0 l&rsquo;achat d&rsquo;un VAE d&rsquo;occasion.<\/strong> \u00c0 Montpellier, une initiative remarquable a \u00e9t\u00e9 mise en place pour encourager l&rsquo;adoption de modes de transport alternatifs et durables. Avec une <strong>subvention de 200\u20ac maximum<\/strong>, <strong>Montpellier M\u00e9diterran\u00e9e M\u00e9tropole<\/strong> offre un <strong>soutien financier aux r\u00e9sidents souhaitant acqu\u00e9rir un v\u00e9lo \u00e0 assistance \u00e9lectrique (VAE) d&rsquo;occasion<\/strong> ou un <strong>kit d&rsquo;\u00e9lectrification<\/strong>. Dans cet article, nous allons <strong>explorer en d\u00e9tail les conditions et les \u00e9tapes \u00e0 suivre<\/strong> pour b\u00e9n\u00e9ficier de cette aide pr\u00e9cieuse.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"379\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2024\/03\/aide-a-lachat-dun-vae-doccasion-montpellier-1024x379.jpg\" alt=\"Tout ce que vous devez savoir sur l'aide \u00e0 l'achat d'un VAE d'occasion ou d'un kit d'\u00e9lectrification de 200\u20ac \u00e0 Montpellier\" class=\"wp-image-111129\" srcset=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2024\/03\/aide-a-lachat-dun-vae-doccasion-montpellier-1024x379.jpg 1024w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2024\/03\/aide-a-lachat-dun-vae-doccasion-montpellier-416x154.jpg 416w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2024\/03\/aide-a-lachat-dun-vae-doccasion-montpellier-300x111.jpg 300w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2024\/03\/aide-a-lachat-dun-vae-doccasion-montpellier-768x284.jpg 768w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2024\/03\/aide-a-lachat-dun-vae-doccasion-montpellier-1536x569.jpg 1536w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2024\/03\/aide-a-lachat-dun-vae-doccasion-montpellier.jpg 1702w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\"><strong>200\u20ac d&rsquo;aide \u00e0 l&rsquo;achat d&rsquo;un v\u00e9lo \u00e9lectrique d&rsquo;occasion ou d&rsquo;un kit d&rsquo;\u00e9lectrification<\/strong> : <strong>Conditions d&rsquo;\u00e9ligibilit\u00e9<\/strong><\/h2>\n\n\n\n<p><strong>Pour \u00eatre admissible<\/strong> \u00e0 cette subvention, <strong>plusieurs conditions<\/strong> doivent \u00eatre remplies :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>L&rsquo;achat du v\u00e9lo d&rsquo;occasion<\/strong> doit \u00eatre <strong>post\u00e9rieur au 1er f\u00e9vrier 2021<\/strong>, tandis que<strong> l&rsquo;achat du kit d&rsquo;\u00e9lectrification<\/strong> doit \u00eatre <strong>post\u00e9rieur au 28 juillet 2021<\/strong>. <em>(facture faisant foi)<\/em><\/li>\n\n\n\n<li><strong>L&rsquo;achat doit \u00eatre effectu\u00e9<\/strong> dans un <strong>commerce situ\u00e9 dans la M\u00e9tropole de Montpellier<\/strong>. Les <strong>achats en ligne ne sont pas \u00e9ligibles<\/strong>. (Exemple Ride &amp; Co ou <a href=\"https:\/\/www.giant-montpellier-perols.fr\/fr\" target=\"_blank\" rel=\"noopener\">GIANT Store Montpellier P\u00e9rols<\/a>)<\/li>\n\n\n\n<li>Ce dispositif est <strong>cumulable avec les <a href=\"https:\/\/rideandco.com\/giant\/aides-a-lachat-dun-velo-montpellier-toulouse\/\">autres aides existantes<\/a><\/strong> soumises \u00e0 conditions : dispositif de l&rsquo;\u00c9tat de la R\u00e9gion Occitanie et du Conseil D\u00e9partemental de l&rsquo;H\u00e9rault.<\/li>\n\n\n\n<li>Le montant de la subvention est de <strong>200 \u20ac maximum <\/strong>dans la limite de <strong>50 % de la valeur d&rsquo;achat<\/strong> du v\u00e9lo d&rsquo;occasion ou du kit d&rsquo;\u00e9lectrification.<\/li>\n\n\n\n<li>Le b\u00e9n\u00e9ficiaire doit <strong>avoir plus de 18 ans<\/strong>, ou \u00eatre le <strong>repr\u00e9sentant l\u00e9gal<\/strong> d&rsquo;un <strong>mineur <\/strong>de <strong>plus de 16 ans.<\/strong><\/li>\n\n\n\n<li>S&rsquo;engager \u00e0 <strong>ne pas revendre le v\u00e9lo<\/strong> <strong>avant trois ans<\/strong> est une condition indispensable.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>200\u20ac d&rsquo;aide \u00e0 l&rsquo;achat d&rsquo;un v\u00e9lo d&rsquo;occasion \u00e0 assistance \u00e9lectrique ou d&rsquo;un kit d&rsquo;\u00e9lectrification<\/strong> : <strong>V\u00e9los \u00e9ligibles<\/strong><\/h2>\n\n\n\n<p>Les <strong>v\u00e9hicules concern\u00e9s <\/strong>par ce dispositif de subvention sont :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les<strong> v\u00e9los \u00e0 assistance \u00e9lectrique d\u2019occasion <\/strong>(<strong>y compris les v\u00e9los cargos \u00e9lectriques<\/strong>) et <strong>kits d\u2019\u00e9lectrification <\/strong>conformes \u00e0 la r\u00e9glementation en vigueur selon laquelle les termes \u00ab v\u00e9lo \u00e0 assistance \u00e9lectrique \u00bb ou \u00ab kit \u00e9lectrique sur v\u00e9lo \u00bb s\u2019entendent au sens de la directive europ\u00e9enne N\u00b0 2002\/24\/CE du 18 mars 2002 : \u00ab cycle \u00e0 p\u00e9dalage assist\u00e9, \u00e9quip\u00e9 d\u2019un <strong>moteur auxiliaire \u00e9lectrique d\u2019une puissance nominale continue maximale de 0,25 Kilowatt <\/strong>dont l&rsquo;alimentation est r\u00e9duite progressivement et finalement interrompue lorsque le v\u00e9hicule atteint une vitesse de 25 Km\/h, ou plus t\u00f4t, si le cycliste arr\u00eate de p\u00e9daler \u00bb. (Correspondance norme fran\u00e7aise en vigueur : NF EN 15194 (depuis mai 2009)).<\/li>\n\n\n\n<li>Les <strong>diff\u00e9rents \u00e9quipements<\/strong>, aff\u00e9rents \u00e0 la pratique et joints \u00e0 la facture d\u2019achat du v\u00e9lo, tels que : Casque, Antivol, Dispositif d\u2019\u00e9clairage, Tenue r\u00e9fl\u00e9chissante.<\/li>\n<\/ul>\n\n\n\n<p><em>Nota : Les normes \u00e9tant susceptibles d\u2019\u00e9volution, se r\u00e9f\u00e9rer aux derni\u00e8res normes en vigueur.<br><\/em>Le <strong><a href=\"https:\/\/rideandco.com\/giant\/certificat-de-conformite\/\">certificat d\u2019homologation<\/a><\/strong> correspondant au v\u00e9lo ou au kit souhait\u00e9 sera demand\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Engagements et d\u00e9marches :<\/strong><\/h2>\n\n\n\n<p>Le processus pour b\u00e9n\u00e9ficier de cette aide se d\u00e9roule en plusieurs \u00e9tapes :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Demande de subvention<\/strong> : Le b\u00e9n\u00e9ficiaire doit <strong>soumettre un dossier complet \u00e0 Montpellier M\u00e9diterran\u00e9e M\u00e9tropole<\/strong>, <strong>incluant divers documents<\/strong> tels que le <strong>RIB<\/strong>, une <strong>pi\u00e8ce d&rsquo;identit\u00e9<\/strong>, la <strong>facture d&rsquo;achat<\/strong>, le <strong>certificat d&rsquo;homologation<\/strong>, etc via le site <a href=\"https:\/\/eservices.montpellier3m.fr\/aides-aux-entreprises\/subvention-vae-occasion\/\" target=\"_blank\" rel=\"noopener\">eservices.montpellier3m.fr<\/a> ou directement aux guichets uniques de la M\u00e9tropole \u00e0 l&rsquo;adresse : <a href=\"https:\/\/www.google.com\/maps?rlz=1C1GCEU_frFR1074FR1074&amp;gs_lcrp=EgZjaHJvbWUyBggAEEUYOdIBBzY1OGowajeoAgCwAgA&amp;um=1&amp;ie=UTF-8&amp;fb=1&amp;gl=fr&amp;sa=X&amp;geocode=KWHxbJZBrrYSMUsmrveMTImI&amp;daddr=50+Pl.+de+Zeus,+34000+Montpellier\" target=\"_blank\" rel=\"noopener\">MONTPELLIER M\u00c9DITERRAN\u00c9E M\u00c9TROPOLE \u2013 Direction des mobilit\u00e9s &#8211; 50 PLACE DE ZEUS 34000 MONTPELLIER<\/a><\/li>\n\n\n\n<li><strong>Instruction de la demande <\/strong>: Les services de Montpellier M\u00e9diterran\u00e9e M\u00e9tropole examinent la demande et v\u00e9rifient la conformit\u00e9 aux conditions d&rsquo;\u00e9ligibilit\u00e9.<\/li>\n\n\n\n<li><strong>Versement de la subvention<\/strong> : Une fois la demande approuv\u00e9e, la subvention est vers\u00e9e au b\u00e9n\u00e9ficiaire.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Modalit\u00e9s de versement de la subvention : <\/h2>\n\n\n\n<p>L\u2019octroi de la subvention intervient en deux \u00e9tapes.<\/p>\n\n\n\n<p><strong>Demande de subvention :<br><\/strong>Le b\u00e9n\u00e9ficiaire devra<strong> faire parvenir son dossier de demande de subvention<\/strong>, via la<a href=\"https:\/\/eservices.montpellier3m.fr\/aides-aux-entreprises\/subvention-vae-occasion\/\" target=\"_blank\" rel=\"noopener\"> plateforme e-service<\/a>, par courrier ou <a href=\"https:\/\/www.google.com\/maps?rlz=1C1GCEU_frFR1074FR1074&amp;gs_lcrp=EgZjaHJvbWUqBggAEEUYOzIGCAAQRRg70gEIMTA2OGowajeoAgCwAgA&amp;um=1&amp;ie=UTF-8&amp;fb=1&amp;gl=fr&amp;sa=X&amp;geocode=KWHxbJZBrrYSMUsmrveMTImI&amp;daddr=50+Pl.+de+Zeus,+34000+Montpellier\" target=\"_blank\" rel=\"noopener\">\u00e0 l\u2019accueil de l\u2019h\u00f4tel de Montpellier M\u00e9diterran\u00e9e M\u00e9tropole<\/a> en y <strong>joignant les documents <\/strong>suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un <strong>Relev\u00e9 d\u2019Identit\u00e9 Bancaire<\/strong> au format banque (RIB) du compte \u00e0 son nom, sur lequel l\u2019aide sera vers\u00e9e par virement<\/li>\n\n\n\n<li>La <strong>copie d\u2019une pi\u00e8ce d\u2019identit\u00e9 du demandeur en cours de validit\u00e9<\/strong> (carte identit\u00e9, passeport, permis de conduire, \u2026)<\/li>\n\n\n\n<li>Le <strong>certificat d\u2019homologation <\/strong>du <strong>v\u00e9lo \u00e0 assistance \u00e9lectrique d\u2019occasion<\/strong><\/li>\n\n\n\n<li>La <strong>facture du v\u00e9lo \u00e0 Assistance \u00c9lectrique neuf<\/strong>, le cas \u00e9ch\u00e9ant <strong>accompagn\u00e9 de la (des) facture(s) d\u00e9taill\u00e9e(s) d\u2019achat des mat\u00e9riels li\u00e9s \u00e0 la pratique<\/strong> et d\u00e9taill\u00e9s dans l\u2019article 2, \u00e0 son nom propre, post\u00e9rieure(s) \u00e0 la mise en place du pr\u00e9sent dispositif et correspondant \u00e0 un (des) achat(s) effectu\u00e9(s) physiquement aupr\u00e8s d\u2019un revendeur professionnel localis\u00e9 sur la M\u00e9tropole de Montpellier (les achats par Internet \u00e9tant exclus)<\/li>\n\n\n\n<li>Le <strong>num\u00e9ro unique du V\u00e9lo<\/strong> inscrit dans le \u00ab fichier national unique des cycles identifi\u00e9s \u00bb et correspondant au <strong>gravage d\u2019icelui<\/strong><sup data-fn=\"f28d0f3d-0515-4c04-9d1e-e005b5c4cef4\" class=\"fn\"><a href=\"#f28d0f3d-0515-4c04-9d1e-e005b5c4cef4\" id=\"f28d0f3d-0515-4c04-9d1e-e005b5c4cef4-link\">1<\/a><\/sup><\/li>\n\n\n\n<li>L\u2019engagement par une<strong> attestation sur l\u2019honneur \u00e0 ne percevoir qu\u2019une seule aide par utilisateur<\/strong> et \u00e0 <strong>ne pas revendre le VAE<\/strong> achet\u00e9 gr\u00e2ce \u00e0 l\u2019aide obtenue <strong>avant trois ans,<\/strong> sous peine de devoir la restituer \u00e0 Montpellier M\u00e9diterran\u00e9e M\u00e9tropole<\/li>\n\n\n\n<li>Un<strong> justificatif de domicile<\/strong> au nom et pr\u00e9nom du demandeur, de sa r\u00e9sidence principale <strong>datant de moins de trois mois<\/strong> \u00e0 la date d\u2019achat du VAE (facture de t\u00e9l\u00e9phone fixe ou mobile, ou d\u2019abonnement internet, ou facture d\u2019eau, d\u2019\u00e9lectricit\u00e9, \u00e0 l\u2019exclusion des attestations d\u2019h\u00e9bergement).<\/li>\n\n\n\n<li>Le <strong>r\u00e8glement<\/strong> de l&rsquo;aide d\u00fbment <strong>dat\u00e9 et sign\u00e9<\/strong>. <a href=\"https:\/\/www.montpellier3m.fr\/sites\/default\/files\/2023-11\/2023_12_reglement_attribution_aide_financiere_vaeoccasion.pdf\" target=\"_blank\" rel=\"noopener\">(T\u00e9l\u00e9chargez le r\u00e8glement ici) <\/a><\/li>\n<\/ul>\n\n\n\n<p><br><strong>Cas particulier des demandeurs ayant command\u00e9 le v\u00e9lo ou le kit mais \u00e9tant en attente de sa r\u00e9ception et de son gravage<br>Un bon de commande \u00e9dit\u00e9 par les services m\u00e9tropolitains<\/strong> est <strong>mis \u00e0 disposition des demandeurs.<\/strong> Celui-ci, <strong>dat\u00e9 et sign\u00e9 \u00e0 la fois par le demandeur et le repr\u00e9sentant l\u00e9gal du v\u00e9lociste<\/strong>, <strong>devra imp\u00e9rativement accompagner <\/strong>les diff\u00e9rentes <strong>pi\u00e8ces du dossier<\/strong> list\u00e9es ci-dessus <strong>au moment du d\u00e9p\u00f4t <\/strong>de celui-ci, d\u00e8s r\u00e9ception, <strong>gravage et r\u00e8glement du reste \u00e0 charge au v\u00e9lociste<\/strong>.<br>Le <strong>d\u00e9p\u00f4t du dossier par le demandeur<\/strong> pourra donc dans ce cadre \u00eatre effectu\u00e9 <strong>post\u00e9rieurement \u00e0 la date de fin du dispositif<\/strong>, si Montpellier M\u00e9diterran\u00e9e M\u00e9tropole d\u00e9cide d\u2019y mettre fin.<\/p>\n\n\n\n<p><strong>Versement de la subvention<\/strong> :<\/p>\n\n\n\n<p><strong>L\u2019aide de 200 \u20ac maximum<\/strong> est <strong>vers\u00e9e apr\u00e8s instruction de la demande<\/strong> par les services de Montpellier M\u00e9diterran\u00e9e M\u00e9tropole et <strong>sous r\u00e9serve du respect des conditions d\u2019\u00e9ligibilit\u00e9 au dispositif<\/strong>. Le demandeur est inform\u00e9 par courrier des suites donn\u00e9es \u00e0 sa demande.<\/p>\n\n\n\n<p><strong>Restitution et sanctions :<\/strong> <\/p>\n\n\n\n<p><strong>En cas de non-respect des conditions<\/strong>, notamment la <strong>revente du v\u00e9lo avant trois ans<\/strong>, le <strong>b\u00e9n\u00e9ficiaire doit restituer la subvention<\/strong> \u00e0 Montpellier M\u00e9diterran\u00e9e M\u00e9tropole. Le <strong>d\u00e9tournement de la subvention<\/strong> peut entra\u00eener des sanctions l\u00e9gales, notamment <strong>en cas d\u2019achat pour revente<\/strong>, est susceptible d\u2019\u00eatre <strong>qualifi\u00e9 d\u2019abus de confiance<\/strong> et<strong> rend son auteur passible des<\/strong> <strong>sanctions <\/strong>pr\u00e9vues par l\u2019article 314-1 du code p\u00e9nal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aide \u00e0 l&rsquo;achat Montpellier : Comment d\u00e9poser mon dossier d&rsquo;aide \u00e0 l&rsquo;achat d&rsquo;un VAE d&rsquo;occasion ou d&rsquo;un kit d&rsquo;\u00e9lectrification de 200\u20ac <\/h2>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2024\/03\/deposer-mon-dosier-daide-a-lachat-dun-VAE-doccasion-1-1024x576.png\" alt=\"Aide \u00e0 l'achat d'un VAE d'occasion processus de d\u00e9p\u00f4t d'aide\" class=\"wp-image-111132\" style=\"width:772px;height:auto\"\/><\/figure><\/div>\n\n\n<p>En conclusion, <strong>l&rsquo;aide \u00e0 l&rsquo;achat d&rsquo;un v\u00e9lo \u00e0 assistance \u00e9lectrique d&rsquo;occasion <\/strong>ou d&rsquo;un <strong>kit d&rsquo;\u00e9lectrification de 200\u20ac offerte<\/strong> par Montpellier M\u00e9diterran\u00e9e M\u00e9tropole repr\u00e9sente une <strong>opportunit\u00e9 exceptionnelle pour les r\u00e9sidents de la m\u00e9tropole<\/strong> souhaitant adopter une mobilit\u00e9 plus durable.<strong> En combinant cette subvention avec les <a href=\"http:\/\/localhost\/egrim\/aides-pour-lachat-dun-velo-electrique\/\" target=\"_blank\" rel=\"noopener\">autres aides disponibles<\/a><\/strong> au niveau <strong>national<\/strong>, <strong>r\u00e9gional <\/strong>et <strong>d\u00e9partemental<\/strong>, telles que celles propos\u00e9es par l&rsquo;\u00c9tat, le d\u00e9partement de l&rsquo;H\u00e9rault et la r\u00e9gion Occitanie, <strong>les citoyens peuvent b\u00e9n\u00e9ficier de soutiens financiers significatifs<\/strong> pour l&rsquo;acquisition de leur v\u00e9lo \u00e9lectrique.<\/p>\n\n\n\n<p>Sur notre site internet, <a href=\"https:\/\/rideandco.com\/giant\" data-type=\"link\" data-id=\"https:\/\/rideandco.com\/giant\">rideandco.com<\/a>, vous trouverez une <a href=\"http:\/\/localhost\/egrim\/aides-a-lachat-velo-electrique\/\" target=\"_blank\" rel=\"noopener\">mine d&rsquo;informations sur les diff\u00e9rentes aides \u00e0 l&rsquo;achat de v\u00e9los \u00e9lectriques,<\/a> qu&rsquo;ils soient neufs ou d&rsquo;occasion. Nous mettons \u00e0 votre disposition toutes les ressources n\u00e9cessaires pour comprendre et profiter de ces dispositifs d&rsquo;aide, y compris les d\u00e9tails sur les conditions d&rsquo;\u00e9ligibilit\u00e9, les d\u00e9marches \u00e0 suivre pour obtenir la subvention, ainsi que des conseils pratiques pour choisir le v\u00e9lo \u00e9lectrique qui vous convient le mieux.<\/p>\n\n\n\n<p>Que vous recherchiez une aide \u00e0 l&rsquo;achat de v\u00e9lo \u00e9lectrique d&rsquo;occasion, une subvention pour un VAE neuf, ou tout autre soutien financier, notre site est votre destination unique pour explorer toutes les opportunit\u00e9s disponibles. N&rsquo;h\u00e9sitez pas \u00e0 visiter<a href=\"https:\/\/rideandco.com\/giant\" data-type=\"link\" data-id=\"https:\/\/rideandco.com\/giant\"> rideandco.com<\/a> pour d\u00e9couvrir comment vous pouvez b\u00e9n\u00e9ficier de ces aides et contribuer \u00e0 une mobilit\u00e9 plus respectueuse de l&rsquo;environnement.<\/p>\n\n\n<ol class=\"wp-block-footnotes\"><li id=\"f28d0f3d-0515-4c04-9d1e-e005b5c4cef4\">Obligation l\u00e9gale depuis le 1\/1\/2021. <a href=\"#f28d0f3d-0515-4c04-9d1e-e005b5c4cef4-link\" aria-label=\"Aller \u00e0 la note de bas de page 1\">\u21a9\ufe0e<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Plongeons dans le monde de la mobilit\u00e9 durable avec un sujet d&rsquo;importance capitale pour les r\u00e9sidents de Montpellier et sa m\u00e9tropole : l&rsquo;aide \u00e0 l&rsquo;achat d&rsquo;un VAE d&rsquo;occasion. \u00c0 Montpellier, une initiative remarquable a \u00e9t\u00e9 mise en place pour encourager l&rsquo;adoption de modes de transport alternatifs et durables. Avec une subvention de 200\u20ac maximum, Montpellier [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":115529,"parent":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"two_page_speed":[],"footnotes":"[{\"content\":\"Obligation l\u00e9gale depuis le 1\/1\/2021.\",\"id\":\"f28d0f3d-0515-4c04-9d1e-e005b5c4cef4\"}]"},"categories":[350,369,419],"tags":[],"class_list":["post-111124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guide-et-conseils","category-ride-and-learn","category-guide-dachat"],"acf":[],"_links":{"self":[{"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/posts\/111124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/comments?post=111124"}],"version-history":[{"count":1,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/posts\/111124\/revisions"}],"predecessor-version":[{"id":115530,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/posts\/111124\/revisions\/115530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/media\/115529"}],"wp:attachment":[{"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/media?parent=111124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/categories?post=111124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/tags?post=111124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}