{"id":106338,"date":"2023-02-15T14:54:29","date_gmt":"2023-02-15T13:54:29","guid":{"rendered":"http:\/\/localhost\/egrim\/?p=106338"},"modified":"2024-10-24T17:12:18","modified_gmt":"2024-10-24T15:12:18","slug":"caracteristiques-principales-velo-electrique","status":"publish","type":"post","link":"https:\/\/rideandco.com\/giant\/caracteristiques-principales-velo-electrique\/","title":{"rendered":"Quelles sont les caract\u00e9ristiques principales d&rsquo;un v\u00e9lo \u00e9lectrique ?"},"content":{"rendered":"\n<p>Les <a href=\"https:\/\/rideandco.com\/giant\/choix-velo-electrique\/\"><strong>v\u00e9los \u00e9lectriques<\/strong><\/a> <strong>sont de plus en plus populaires<\/strong>, tant pour les <strong>d\u00e9placements quotidiens<\/strong> que pour les <strong>loisirs<\/strong>. Mais alors quelles sont les<strong> caract\u00e9ristiques principales d&rsquo;un v\u00e9lo \u00e9lectrique<\/strong> ? <strong>Et  comment fonctionnent-ils ?<\/strong> Dans cet article, nous r\u00e9pondrons \u00e0 ces questions et \u00e0 bien d&rsquo;autres, en d\u00e9crivant les <strong>principales caract\u00e9ristiques des v\u00e9los \u00e9lectriques<\/strong>. Lisez la suite pour en savoir plus sur ce nouveau mode de transport passionnant !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tout savoir sur les caract\u00e9ristiques principales d&rsquo;un v\u00e9lo \u00e9lectrique <\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Quel est la diff\u00e9rence entre un v\u00e9lo classique et un v\u00e9lo \u00e9lectrique ?<\/h3>\n\n\n\n<p>Les<strong> v\u00e9los \u00e9lectriques<\/strong> deviennent le moyen de transport le plus populaire, permettant aux cyclistes de <strong>parcourir facilement de plus longues distances<\/strong> que les v\u00e9los traditionnels. Ils se pr\u00e9sentent sous de <strong>nombreuses formes et tailles<\/strong>, comme par exemple les <a href=\"https:\/\/rideandco.com\/giant\/vtt-electrique-qu-est-ce-que-cest\/\">VTT \u00e9lectriques<\/a>, les <a href=\"https:\/\/rideandco.com\/giant\/top-5-des-vtc-electriques\/\">VTC \u00e9lectriques<\/a>, les <a href=\"https:\/\/rideandco.com\/giant\/meilleurs-velos-de-ville-electriques\/\">v\u00e9los de ville \u00e9lectriques<\/a> ou encore les <a href=\"https:\/\/rideandco.com\/giant\/velo-cargo-electrique-prix-aides-guide-2023\/\">v\u00e9los cargos \u00e9lectriques<\/a>.<\/p>\n\n\n<p>Aucun produit trouv\u00e9.<\/p>\n\n\n<p><strong>Ce qui distingue les v\u00e9los \u00e9lectriques des v\u00e9los traditionnels<\/strong>, c&rsquo;est leur <strong>puissance<\/strong>. <strong>Plut\u00f4t que de compter <\/strong>uniquement sur votre<strong> force physique pour avancer<\/strong>, les <strong>v\u00e9los \u00e9lectriques sont aliment\u00e9s par une batterie<\/strong> qui peut \u00eatre<strong> recharg\u00e9e<\/strong> simplement en la <strong>branchant sur une prise de courant<\/strong>. Gr\u00e2ce \u00e0 cette technologie, <strong>les cyclistes utilisant des v\u00e9los \u00e9lectriques peuvent aller plus loin<\/strong> et <strong>explorer plus de terrain<\/strong> avec <strong>facilit\u00e9<\/strong>. <\/p>\n\n\n\n<p>Que vous cherchiez un <strong>moyen de transport quotidien pour <a href=\"https:\/\/rideandco.com\/giant\/10-bonnes-raisons-de-choisir-un-velotaf\/\">vous rendre au travail<\/a><\/strong> ou que vous souhaitiez <strong>explorer des sentiers hors route<\/strong> lors d&rsquo;une escapade le week-end, les <strong>v\u00e9los \u00e9lectriques offrent l&rsquo;\u00e9quilibre parfait entre la vitalit\u00e9 assist\u00e9e et la vitesse humaine<\/strong> &#8211; il n&rsquo;est pas \u00e9tonnant que tant de cyclistes optent pour l&rsquo;\u00e9lectrique !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comment fonctionne le moteur d&rsquo;un v\u00e9lo \u00e9lectrique ?<\/h2>\n\n\n\n<p>De nombreux v\u00e9los \u00e9lectriques sont \u00e9quip\u00e9s d&rsquo;une technologie de<strong> motorisation qui facilite le p\u00e9dalage<\/strong> et le rend <strong>plus efficace<\/strong>. Cette technologie de <strong><a href=\"https:\/\/rideandco.com\/giant\/moteurs-de-velos-electriques\/\">motorisation <\/a><\/strong>est g\u00e9n\u00e9ralement <strong>fournie <\/strong>par des <strong>fabricants de moteurs tels que <a href=\"https:\/\/www.bosch-ebike.com\/fr\/\" target=\"_blank\" rel=\"noopener\">Bosch<\/a>, <a href=\"https:\/\/www.yamaha-motor.eu\/fr\/fr\/b2b\/e-bike\/#\/\" target=\"_blank\" rel=\"noopener\">Yamaha <\/a>ou <a href=\"https:\/\/lifestylebike.shimano.com\/fr\/\" target=\"_blank\" rel=\"noopener\">Shimano<\/a>,<\/strong> et elle permet au cycliste de<strong> compl\u00e9ter son propre couple de p\u00e9dales<\/strong> afin de<strong> maintenir des vitesses plus \u00e9lev\u00e9es<\/strong> ou de <strong>gravir des collines<\/strong> avec une relative <strong>facilit\u00e9<\/strong>. Le <strong>moteur <\/strong>est g\u00e9n\u00e9ralement <strong>limit\u00e9 sur les v\u00e9los \u00e9lectriques<\/strong> \u00e0 une<strong> vitesse maximale de 25 km\/h<\/strong>, mais ce <strong>couple de p\u00e9dale suppl\u00e9mentaire<\/strong> peut toujours faire une <strong>grande diff\u00e9rence en cas de mont\u00e9e ou de vent contraire<\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"183\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2023\/01\/moteur-bosch-velo-electrique.jpg\" alt=\"Caract\u00e9ristiques principales d'un v\u00e9lo \u00e9lectrique : Moteur\" class=\"wp-image-106352\" style=\"object-fit:cover\"\/><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">Comment fonctionne la batterie d&rsquo;un v\u00e9lo \u00e9lectrique ?<\/h2>\n\n\n\n<p>La <strong>batterie d&rsquo;un v\u00e9lo \u00e9lectrique<\/strong> est au<strong> c\u0153ur de son fonctionnement<\/strong>. Elle <strong>alimente le moteur \u00e0 assistance \u00e9lectrique<\/strong> pour <strong>propulser le cycliste \u00e0 des vitesses plus rapides<\/strong> que celles qu&rsquo;il peut atteindre uniquement en p\u00e9dalant. Les <strong>batteries <\/strong>sont g\u00e9n\u00e9ralement <strong>rechargeables <\/strong>et peuvent \u00eatre <strong>situ\u00e9es soit dans la tige du si\u00e8ge<\/strong>, soit \u00e0<strong> l&rsquo;arri\u00e8re du v\u00e9lo<\/strong>. Elles sont <strong>parfois int\u00e9gr\u00e9es aux cadres<\/strong> et <strong>offrent une autonomie allant jusqu&rsquo;\u00e0 100 km ou plus<\/strong> selon le mod\u00e8le de v\u00e9lo et la fa\u00e7on dont elle est utilis\u00e9e.<\/p>\n\n\n\n<p>Il y a <strong>plusieurs points cl\u00e9s<\/strong> \u00e0 prendre en compte lorsque vous <strong>achetez un v\u00e9lo \u00e9lectrique<\/strong> et que vous apprenez \u00e0 conna\u00eetre les <strong>batteries<\/strong>. Il est <strong>important <\/strong>de <strong>conna\u00eetre la capacit\u00e9 de sa batterie<\/strong>, c&rsquo;est-\u00e0-dire le <strong>nombre de kilom\u00e8tres <\/strong>qu&rsquo;elle peut fournir <strong>avant de se d\u00e9charger<\/strong>.<strong> Certaines batteries sont amovibles<\/strong> et <strong>peuvent \u00eatre retir\u00e9es<\/strong> du cadre pour <strong>charger \u00e0 l\u2019int\u00e9rieur<\/strong> <strong>ou \u00e0 proximit\u00e9<\/strong> imm\u00e9diate du v\u00e9lo. <strong>D&rsquo;autres batteries sont int\u00e9gr\u00e9es au cadre<\/strong> et doivent \u00eatre <strong>recharg\u00e9es par une prise murale sp\u00e9ciale<\/strong>. La <strong>dur\u00e9e de vie d&rsquo;une batterie<\/strong> est g\u00e9n\u00e9ralement comprise<strong> entre 500 et 1500 cycles de charge\/d\u00e9charge<\/strong>.<\/p>\n\n\n\n<p>Pour conna\u00eetre l&rsquo;\u00e9tat de votre batterie et bien l&rsquo;entretenir pour augmenter sa dur\u00e9e de vie, suivez <a href=\"https:\/\/rideandco.com\/giant\/tester-une-batterie-de-velo-electrique\/\">nos conseils de PRO sur Ride &amp; Co<\/a>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2023\/01\/batterie-vitesse-velo-electrique-1024x576.jpg\" alt=\"Caract\u00e9ristiques principales d'un v\u00e9lo \u00e9lectrique : batterie\" class=\"wp-image-106348\" style=\"width:522px;height:293px\" srcset=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2023\/01\/batterie-vitesse-velo-electrique-1024x576.jpg 1024w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2023\/01\/batterie-vitesse-velo-electrique-416x234.jpg 416w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2023\/01\/batterie-vitesse-velo-electrique-300x169.jpg 300w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2023\/01\/batterie-vitesse-velo-electrique-768x432.jpg 768w, https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2023\/01\/batterie-vitesse-velo-electrique.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">Quelle est la limitation de vitesse de l&rsquo;assistance d&rsquo;un v\u00e9lo \u00e9lectrique ?<\/h2>\n\n\n\n<p>Les <strong>v\u00e9los \u00e9lectriques<\/strong> sont de plus en plus populaires pour les <strong>d\u00e9placements domicile-travail<\/strong>, mais comme il existe aussi des <a href=\"https:\/\/rideandco.com\/giant\/nouveaute-moustache-bike\/\"><strong>speed-bikes<\/strong><\/a>, les conducteurs doivent<strong> faire attention \u00e0 rester du bon c\u00f4t\u00e9 de la loi<\/strong> lorsqu&rsquo;ils se d\u00e9placent \u00e0 grande vitesse.<\/p>\n\n\n\n<p>Les <strong>speed-bikes<\/strong> sont \u00e9quip\u00e9s de <strong>moteurs plus puissants<\/strong> qui peuvent atteindre <strong>48 km\/h<\/strong>, tandis que certains <strong>scooters \u00e9lectriques<\/strong> sont capables de <strong>rouler encore plus vite. Contrairement aux v\u00e9los \u00e9lectriques, les speeds-bikes<\/strong> doivent obligatoirement <strong>\u00eatre immatricul\u00e9s<\/strong> et <strong>assur\u00e9s, <\/strong>et le <strong>cycliste conducteur<\/strong> doit au minimum <strong>avoir le permis B, A ou AM<\/strong> et \u00eatre <strong>\u00e9quip\u00e9 d&rsquo;un casque et de gants.<\/strong><\/p>\n\n\n\n<p>Les <strong>lois r\u00e9gissant les limites de vitesse des v\u00e9los \u00e9lectriques varient d&rsquo;un pays \u00e0 l&rsquo;autre<\/strong> (Maximum <strong>25Km\/h pour les v\u00e9los \u00e9lectriques en Europe<\/strong>) et il est important que les <strong>cyclistes se renseignent sur les lois locales<\/strong> afin de respecter les <strong>restrictions de vitesse<\/strong>.<\/p>\n\n\n\n<p>Il convient \u00e9galement de <strong>respecter les limitations de vitesse<\/strong> des v\u00e9los \u00e9lectriques lorsqu&rsquo;ils circulent sur des <strong>pistes cyclables<\/strong> dont la vitesse est inf\u00e9rieure \u00e0 25 km\/h. Dans le cas contraire, les cyclistes courent le risque de recevoir une amende ou de se voir confisquer leur v\u00e9lo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quel est le poids d&rsquo;un v\u00e9lo \u00e9lectrique ?<\/h2>\n\n\n\n<p>Les<strong> v\u00e9los \u00e9lectriques sont assez populaires <\/strong>de nos jours en raison de leur <strong>commodit\u00e9 et de leur aspect pratique<\/strong>, mais beaucoup<strong> ignorent leurs poids<\/strong>. La plupart des <strong>v\u00e9los \u00e9lectriques sont \u00e9quip\u00e9s de composants l\u00e9gers<\/strong> qui constituent la <strong>majeure partie<\/strong> de leur poids (<em>freins, b\u00e9quille, chaine.<\/em>..),<strong> mais ils comprennent<\/strong> \u00e9galement des composants tels que le <strong>cadre<\/strong>, la <strong>batterie <\/strong>et le <strong>moteur<\/strong>, ce qui peux vite<strong> faire passer la barre des 20kg<\/strong> aux v\u00e9los \u00e9lectriques. Ils sont donc <strong>beaucoup plus lourds qu&rsquo;une bicyclette classique<\/strong>, mais la <strong>puissance de traction suppl\u00e9mentaire<\/strong> qu&rsquo;ils procurent lors des randonn\u00e9es <strong>en vaut la peine<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les v\u00e9los \u00e9lectriques, une nouvelle alternative aux voitures ou aux transports publics ?<\/h2>\n\n\n\n<p>Les <strong>v\u00e9los \u00e9lectriques<\/strong> sont devenus le <strong>moyen de transports<\/strong> le plus connus comme solutions de <strong>mobilit\u00e9 douce<\/strong>, contribuant \u00e0 la <strong>transition \u00e9cologique<\/strong>. Ils offrent <strong>la commodit\u00e9 des voitures<\/strong>, mais avec un<strong> impact environnemental nettement moindre<\/strong>. Ces solutions de mobilit\u00e9 douce <strong>r\u00e9duisent les \u00e9missions de CO2<\/strong> par rapport aux modes de transport traditionnels, tels que la voiture et les transports publics. L&rsquo;adoption g\u00e9n\u00e9ralis\u00e9e des v\u00e9los \u00e9lectriques est l&rsquo;un des moyens par lesquels les contributeurs des<strong><a href=\"https:\/\/rideandco.com\/giant\/montpellier-zfe-zone-a-faibles-emissions\/\"> ZFE<\/a><\/strong> peuvent jouer un <strong>r\u00f4le crucial dans la lutte contre le changement climatique<\/strong>. Non seulement ils r\u00e9duisent les \u00e9missions, mais les <strong>v\u00e9los \u00e9lectriques nous permettent de mener un style de vie actif tout en aidant M\u00e8re Nature<\/strong> !<\/p>\n\n\n\n<p>Avec leur popularit\u00e9 croissante, il n&rsquo;est pas surprenant que les <strong>v\u00e9los \u00e9lectriques <\/strong>deviennent le <strong>symbole d&rsquo;un avenir \u00e9cologique r\u00e9ussi<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aides de l&rsquo;Etat pour l&rsquo;achat d&rsquo;un v\u00e9lo \u00e9lectrique<\/h2>\n\n\n\n<p><strong>En France<\/strong>, des <strong>subventions publiques<\/strong> sont disponibles pour <strong>soutenir l&rsquo;achat d&rsquo;un v\u00e9lo \u00e9lectrique<\/strong>. Ces subventions peuvent prendre la forme de <strong>primes <\/strong>ou de <strong>subventions directes<\/strong> et peuvent contribuer \u00e0 <strong>r\u00e9duire consid\u00e9rablement le co\u00fbt d&rsquo;achat d&rsquo;un v\u00e9lo \u00e9lectrique<\/strong>. Les gouvernements comprennent <strong>l&rsquo;importance du passage \u00e0 des options de mobilit\u00e9 plus \u00e9cologiques,<\/strong> et sont donc dispos\u00e9s \u00e0 <strong>contribuer financi\u00e8rement<\/strong> \u00e0 <strong>l&rsquo;acc\u00e9l\u00e9ration de cette transition<\/strong>.<\/p>\n\n\n\n<p>Pour les <strong>habitants de Montpellier<\/strong>, vous pouvez b\u00e9n\u00e9ficier de<strong> plusieurs aides<\/strong> faisant une <strong>r\u00e9duction maximum de 1 250\u20ac<\/strong> . <strong>Pour en savoir plus<\/strong>, rendez-vous sur notre <strong><a href=\"https:\/\/rideandco.com\/giant\/aides-a-lachat-dun-velo-montpellier-toulouse\/\">page d\u00e9di\u00e9e<\/a><\/strong> ou directement aupr\u00e8s des <strong><a href=\"https:\/\/rideandco.com\/giant\/contacts-et-acces\/\">conseillers Ride &amp; Co en magasin<\/a><\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les v\u00e9los \u00e9lectriques ont besoin de plus d&rsquo;entretien que les v\u00e9los classiques ?<\/h2>\n\n\n\n<p><strong>La r\u00e9ponse est non<\/strong>. Les <strong>v\u00e9los \u00e9lectriques n\u00e9cessitent la m\u00eame <a href=\"https:\/\/rideandco.com\/giant\/entretien-dun-velo-electrique-guide-2023\/\">quantit\u00e9 d&rsquo;entretien<\/a> que n&rsquo;importe quel autre v\u00e9lo<\/strong>, mais avec la composante suppl\u00e9mentaire de <strong><a href=\"https:\/\/rideandco.com\/giant\/tester-une-batterie-de-velo-electrique\/\">l&rsquo;entretien p\u00e9riodique de la batterie<\/a><\/strong>. Les <strong>batteries <\/strong>doivent \u00eatre <strong>r\u00e9guli\u00e8rement charg\u00e9es<\/strong> et <strong>stock\u00e9es dans un endroit sec<\/strong> pour <strong>augmenter leur dur\u00e9e de vie<\/strong>. Il est \u00e9galement <strong>important<\/strong> comme pour les v\u00e9los classiques de<strong> proc\u00e9der \u00e0 des v\u00e9rifications r\u00e9guli\u00e8res<\/strong> de votre v\u00e9lo \u00e9lectrique pour<strong> s&rsquo;assurer qu&rsquo;il n&rsquo;y a pas d&rsquo;anomalie.<\/strong><\/p>\n\n\n\n<p>Les v\u00e9los \u00e9lectriques sont une excellente alternative aux voitures ou aux transports publics. Ils sont aliment\u00e9s par une batterie, qui peut \u00eatre recharg\u00e9e en p\u00e9dalant ou en se branchant sur une prise de courant. La vitesse des v\u00e9los \u00e9lectriques est g\u00e9n\u00e9ralement limit\u00e9e \u00e0 25km\/h, mais certains mod\u00e8les peuvent aller plus vite. Ils sont g\u00e9n\u00e9ralement plus lourds que les bicyclettes ordinaires en raison de la batterie et du moteur. Si vous cherchez un moyen \u00e9cologique et amusant de vous d\u00e9placer, un v\u00e9lo \u00e9lectrique vaut vraiment la peine d&rsquo;\u00eatre envisag\u00e9 !<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-bottom is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-video aligncenter\"><video controls src=\"https:\/\/rideandco.com\/giant\/wp-content\/uploads\/2023\/02\/Reels-atelier.mov\"><\/video><\/figure>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les v\u00e9los \u00e9lectriques sont de plus en plus populaires, tant pour les d\u00e9placements quotidiens que pour les loisirs. Mais alors quelles sont les caract\u00e9ristiques principales d&rsquo;un v\u00e9lo \u00e9lectrique ? Et comment fonctionnent-ils ? Dans cet article, nous r\u00e9pondrons \u00e0 ces questions et \u00e0 bien d&rsquo;autres, en d\u00e9crivant les principales caract\u00e9ristiques des v\u00e9los \u00e9lectriques. Lisez la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":115128,"parent":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"two_page_speed":[],"footnotes":""},"categories":[369,350,420],"tags":[],"class_list":["post-106338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ride-and-learn","category-guide-et-conseils","category-velos-electrique"],"acf":[],"_links":{"self":[{"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/posts\/106338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/comments?post=106338"}],"version-history":[{"count":1,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/posts\/106338\/revisions"}],"predecessor-version":[{"id":115129,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/posts\/106338\/revisions\/115129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/media\/115128"}],"wp:attachment":[{"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/media?parent=106338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/categories?post=106338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rideandco.com\/giant\/wp-json\/wp\/v2\/tags?post=106338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}